{"id":15384,"date":"2024-12-04T09:08:28","date_gmt":"2024-12-04T08:08:28","guid":{"rendered":"https:\/\/loscordonesquemeatocadadia.com\/es\/?p=15384"},"modified":"2024-12-04T09:08:28","modified_gmt":"2024-12-04T08:08:28","slug":"el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos","status":"publish","type":"post","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/","title":{"rendered":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos."},"content":{"rendered":"<p>Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII.<\/p>\n<p>En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.<\/p>\n<div style=\"width: 1280px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-15384-1\" width=\"1280\" height=\"720\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2024\/11\/El-Paseo-del-Prado-de-San-Jeronimo-a-finales-del-siglo-XVII.mp4?_=1\" \/><a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2024\/11\/El-Paseo-del-Prado-de-San-Jeronimo-a-finales-del-siglo-XVII.mp4\">https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2024\/11\/El-Paseo-del-Prado-de-San-Jeronimo-a-finales-del-siglo-XVII.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.<\/p>\n","protected":false},"author":2,"featured_media":15381,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[47,48,1,8],"tags":[],"class_list":["post-15384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arquitectura","category-escultura","category-la-emocion-del-arte","category-son-las-cosas-de-la-vida"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"yo te pintaria as\u00ed si yo pudiera\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Los cordones que me ato cada d\u00eda -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda\" \/>\n\t\t<meta property=\"og:description\" content=\"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-12-04T08:08:28+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-12-04T08:08:28+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#blogposting\",\"name\":\"El Paseo del Prado de Madrid y sus aleda\\u00f1os hace 3 siglos. - Los cordones que me ato cada d\\u00eda\",\"headline\":\"El Paseo del Prado de Madrid y sus aleda\\u00f1os hace 3 siglos.\",\"author\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Paseo-Prado-1.jpg\",\"width\":993,\"height\":587},\"datePublished\":\"2024-12-04T09:08:28+01:00\",\"dateModified\":\"2024-12-04T09:08:28+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":2,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#webpage\"},\"articleSection\":\"Arquitectura, Escultura, La emoci\\u00f3n del Arte, Son las cosas de la vida...\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"name\":\"La emoci\\u00f3n del Arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"position\":2,\"name\":\"La emoci\\u00f3n del Arte\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/arquitectura\\\/#listItem\",\"name\":\"Arquitectura\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/arquitectura\\\/#listItem\",\"position\":3,\"name\":\"Arquitectura\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/arquitectura\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#listItem\",\"name\":\"El Paseo del Prado de Madrid y sus aleda\\u00f1os hace 3 siglos.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"name\":\"La emoci\\u00f3n del Arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#listItem\",\"position\":4,\"name\":\"El Paseo del Prado de Madrid y sus aleda\\u00f1os hace 3 siglos.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/arquitectura\\\/#listItem\",\"name\":\"Arquitectura\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\",\"name\":\"Los cordones que me ato cada d\\u00eda\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/\",\"name\":\"yo te pintaria as\\u00ed si yo pudiera\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93f26e5685ea82b42201c127a33bb86aa2a372bbec04d1a3a74cab90e8beb2c0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"yo te pintaria as\\u00ed si yo pudiera\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#webpage\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/\",\"name\":\"El Paseo del Prado de Madrid y sus aleda\\u00f1os hace 3 siglos. - Los cordones que me ato cada d\\u00eda\",\"description\":\"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\\u00edas, podr\\u00e1 verse como se transform\\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Paseo-Prado-1.jpg\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#mainImage\",\"width\":993,\"height\":587},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2024\\\/12\\\/04\\\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\\\/#mainImage\"},\"datePublished\":\"2024-12-04T09:08:28+01:00\",\"dateModified\":\"2024-12-04T09:08:28+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/\",\"name\":\"Los cordones que me ato cada d\\u00eda\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda","description":"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.","canonical_url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#blogposting","name":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda","headline":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos.","author":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"publisher":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2024\/11\/Paseo-Prado-1.jpg","width":993,"height":587},"datePublished":"2024-12-04T09:08:28+01:00","dateModified":"2024-12-04T09:08:28+01:00","inLanguage":"es-ES","commentCount":2,"mainEntityOfPage":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#webpage"},"isPartOf":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#webpage"},"articleSection":"Arquitectura, Escultura, La emoci\u00f3n del Arte, Son las cosas de la vida..."},{"@type":"BreadcrumbList","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/loscordonesquemeatocadadia.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","name":"La emoci\u00f3n del Arte"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","position":2,"name":"La emoci\u00f3n del Arte","item":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/#listItem","name":"Arquitectura"},"previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/#listItem","position":3,"name":"Arquitectura","item":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#listItem","name":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos."},"previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","name":"La emoci\u00f3n del Arte"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#listItem","position":4,"name":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos.","previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/#listItem","name":"Arquitectura"}}]},{"@type":"Organization","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization","name":"Los cordones que me ato cada d\u00eda","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/"},{"@type":"Person","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/","name":"yo te pintaria as\u00ed si yo pudiera","image":{"@type":"ImageObject","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/93f26e5685ea82b42201c127a33bb86aa2a372bbec04d1a3a74cab90e8beb2c0?s=96&d=mm&r=g","width":96,"height":96,"caption":"yo te pintaria as\u00ed si yo pudiera"}},{"@type":"WebPage","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#webpage","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/","name":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda","description":"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#breadcrumblist"},"author":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"creator":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2024\/11\/Paseo-Prado-1.jpg","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#mainImage","width":993,"height":587},"primaryImageOfPage":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/#mainImage"},"datePublished":"2024-12-04T09:08:28+01:00","dateModified":"2024-12-04T09:08:28+01:00"},{"@type":"WebSite","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#website","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/","name":"Los cordones que me ato cada d\u00eda","inLanguage":"es-ES","publisher":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Los cordones que me ato cada d\u00eda -","og:type":"article","og:title":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda","og:description":"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos.","og:url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/","article:published_time":"2024-12-04T08:08:28+00:00","article:modified_time":"2024-12-04T08:08:28+00:00","twitter:card":"summary_large_image","twitter:title":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos. - Los cordones que me ato cada d\u00eda","twitter:description":"Se adjunta video de como fue el paseo del Prado de Madrid a finales del siglo XVII. En unos d\u00edas, podr\u00e1 verse como se transform\u00f3, en lo que hoy son los Paseos del Prado y Recoletos."},"aioseo_meta_data":{"post_id":"15384","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2024-11-27 04:33:01","updated":"2025-06-14 03:45:37","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/\" title=\"La emoci\u00f3n del Arte\">La emoci\u00f3n del Arte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/\" title=\"Arquitectura\">Arquitectura<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tEl Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/loscordonesquemeatocadadia.com\/es"},{"label":"La emoci\u00f3n del Arte","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/"},{"label":"Arquitectura","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/arquitectura\/"},{"label":"El Paseo del Prado de Madrid y sus aleda\u00f1os hace 3 siglos.","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/2024\/12\/04\/el-paseo-del-prado-de-madrid-y-sus-aledanos-hace-3-siglos\/"}],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/15384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/comments?post=15384"}],"version-history":[{"count":2,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/15384\/revisions"}],"predecessor-version":[{"id":15388,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/15384\/revisions\/15388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/media\/15381"}],"wp:attachment":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/media?parent=15384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/categories?post=15384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/tags?post=15384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}