{"id":5089,"date":"2019-04-13T09:00:20","date_gmt":"2019-04-13T08:00:20","guid":{"rendered":"http:\/\/loscordonesquemeatocadadia.com\/es\/?p=5089"},"modified":"2019-04-08T17:15:31","modified_gmt":"2019-04-08T16:15:31","slug":"bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4","status":"publish","type":"post","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/","title":{"rendered":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4."},"content":{"rendered":"<audio class=\"wp-audio-shortcode\" id=\"audio-5089-1\" loop autoplay preload=\"auto\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Lo-Mejor-del-Barroco-M\u00fasica-Barroca-Las-Obras-m\u00e1s-Importantes-y-Famosas-de-la-M\u00fasica-Cl\u00e1sica-3.mp3?_=1\" \/><a href=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Lo-Mejor-del-Barroco-M\u00fasica-Barroca-Las-Obras-m\u00e1s-Importantes-y-Famosas-de-la-M\u00fasica-Cl\u00e1sica-3.mp3\">http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Lo-Mejor-del-Barroco-M\u00fasica-Barroca-Las-Obras-m\u00e1s-Importantes-y-Famosas-de-la-M\u00fasica-Cl\u00e1sica-3.mp3<\/a><\/audio>\n<p style=\"text-align: justify;\">En el solar en el que est\u00e1, la hoy conocida como Plaza\u00a0 Nueva,\u00a0 se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III <em>El Santo<\/em>,\u00a0 cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del\u00a0 Convento Casa Grande de San Francisco, <!--more-->que empez\u00f3 a construirse en los a\u00f1os inmediatos a la reconquista de la ciudad por el mencionado rey cristiano, destacando por sus grandes dimensiones, que exced\u00edan a la actual plaza, siendo el mayor edificio de la ciudad, tras la Catedral.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5102\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/1280px-Plaza_nueva-300x201.jpg\" alt=\"\" width=\"425\" height=\"285\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/1280px-Plaza_nueva-300x201.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/1280px-Plaza_nueva-768x514.jpg 768w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/1280px-Plaza_nueva-1024x686.jpg 1024w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/1280px-Plaza_nueva.jpg 1280w\" sizes=\"auto, (max-width: 425px) 100vw, 425px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Plaza Nueva de Sevilla.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Se fund\u00f3 en 1268 y fue derribado en 1840 durante la regencia de Mar\u00eda Cristina de Borb\u00f3n Dos-Sicilias \u2013madre de Isabel II y mujer de <em>Fernando VII-,<\/em> siendo durante seis siglos, uno de los principales centros religiosos de la ciudad.<\/p>\n<p style=\"text-align: justify;\">En el per\u00edmetro \u00a0conventual, se encontraban la Iglesia -de grandes dimensiones-, el claustro grande, el claustro chico, y algunos\u00a0 patios, jardines, la sala capitular, <strong><em>sala de profundis<\/em><\/strong> \u2013donde se celebraban las asambleas de los frailes- biblioteca, noviciado, cocinas, cuadras, pajares, enfermer\u00edas, huerta, patio donde se cultivaban las plantas para elaborar medicinas, cementerio, <strong>hospeder\u00eda de indias<\/strong> \u2013donde se alojaban los frailes que esperaban para marchar a evangelizar los territorios descubiertos-, el hospital de San Jos\u00e9 de la Venerable Orden Tercera \u2013<em>Hermanos y Hermanas de la Penitencia-, <\/em>y adem\u00e1s una serie de capillas de hermandades y asociaciones que estaban situadas alrededor de los claustros y de la porter\u00eda.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5098\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/convento-de-san-franciso-hoy-plaza-nueva-1-300x203.jpg\" alt=\"\" width=\"455\" height=\"308\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/convento-de-san-franciso-hoy-plaza-nueva-1-300x203.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/convento-de-san-franciso-hoy-plaza-nueva-1.jpg 320w\" sizes=\"auto, (max-width: 455px) 100vw, 455px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Convento Casa Grande de san Francisco.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">El primer contrato importante de Bartolom\u00e9 Esteban Murillo fue el encargo que le hicieron los franciscanos de este convento, <em>Casa Grande de San Francisco<\/em>, \u00a0 para los que trabaj\u00f3 entre los a\u00f1os 1644 y 1646, para decorar el claustro chico. <strong><em>Las trece obras<\/em><\/strong> del artista en el Convento -entre las que se encontraban las doce de este claustro- fueron expoliadas en 1810 por las tropas francesas y llevadas al\u00a0 Real Alc\u00e1zar &#8211;<em>Museo Napole\u00f3nico<\/em>-, desapareciendo junto a otras de varios maestros, excepto la de <strong><em>La Inmaculada Concepci\u00f3n \u201dLa Colosal\u201d<\/em><\/strong>.\u00a0 El convento se incendi\u00f3 en varias ocasiones siendo reconstruido, remoz\u00e1ndolo\u00a0 una vez m\u00e1s tras la salida de los franceses -en agosto de 1812- y abandonado en 1835 con la desamortizaci\u00f3n de Mendizabal, siendo demolido en 1840, dispers\u00e1ndose entonces a otros lugares las pocas obras de arte que quedaban, como\u00a0 <strong><em>el Retablo de los Vizca\u00ednos<\/em><\/strong>, que preside actualmente\u00a0 la <em><strong>Capilla del Sagrario<\/strong><\/em> de la Catedral hispalense. Tambi\u00e9n destacan dos g\u00e1rgolas que se encuentran expuestas en el Museo Arqueol\u00f3gico y un retablo del siglo XVI, de m\u00e1rmol de Carrara, que lleg\u00f3 hasta el Pazo de San Lorenzo de Trasouto, en Galicia, despu\u00e9s de que los condes de Altamira se lo llevaran hasta all\u00ed.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5134\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/capilla-del-sagrario-296x300.jpg\" alt=\"\" width=\"636\" height=\"645\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/capilla-del-sagrario-296x300.jpg 296w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/capilla-del-sagrario.jpg 682w\" sizes=\"auto, (max-width: 636px) 100vw, 636px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Capilla del Sagrario de la Catedral con el Retablo de los Vizca\u00ednos.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Del convento, s\u00f3lo qued\u00f3 en pie, <strong><em>el arquillo del Ayuntamiento<\/em><\/strong>, lugar donde se situar\u00eda hasta el siglo XIX el acceso al atrio del Convento, y <strong><em>la capilla de san Onofre<\/em><\/strong>, oculta entre los edificios construidos en la actualidad.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5101\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/arquillo-del-ayto-visto-desde-plaza-nueva-1-288x300.jpg\" alt=\"\" width=\"288\" height=\"300\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/arquillo-del-ayto-visto-desde-plaza-nueva-1-288x300.jpg 288w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/arquillo-del-ayto-visto-desde-plaza-nueva-1.jpg 531w\" sizes=\"auto, (max-width: 288px) 100vw, 288px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Arquillo visto desde la Plaza Nueva.<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5100\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Arquillo-visto-desde-Plaza-de-san-franciscoFachada-Pza-San-Francisco3-300x218.jpg\" alt=\"\" width=\"300\" height=\"218\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Arquillo-visto-desde-Plaza-de-san-franciscoFachada-Pza-San-Francisco3-300x218.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Arquillo-visto-desde-Plaza-de-san-franciscoFachada-Pza-San-Francisco3.jpg 760w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>Arquillo visto desde la Plaza de san Francisco.<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5121\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Portada-de-San-Onofre-300x229.jpg\" alt=\"\" width=\"300\" height=\"229\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Portada-de-San-Onofre-300x229.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Portada-de-San-Onofre.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Entrada a la capilla de san Onofre.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5112\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Capilla_de_San_Onofre_de_Sevilla-1-300x225.jpg\" alt=\"\" width=\"431\" height=\"323\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Capilla_de_San_Onofre_de_Sevilla-1-300x225.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Capilla_de_San_Onofre_de_Sevilla-1-768x576.jpg 768w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Capilla_de_San_Onofre_de_Sevilla-1.jpg 1024w\" sizes=\"auto, (max-width: 431px) 100vw, 431px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>La capilla de las \u00e1nimas en san Onofre.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">De las obras de Murillo realizadas para este Convento, s\u00f3lo permanece en Sevilla <strong>La <em>Inmaculada Concepci\u00f3n \u201c<\/em>La Colosal\u201d,<\/strong> pintura\u00a0 realizada por el artista hacia el a\u00f1o 1650, \u00a0obra temprana, en la que crea un nuevo prototipo de figura mariana con influencias de Zurbar\u00e1n \u00a0y Ribera.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5116\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada_Concepcion_La_Colosal-210x300.jpg\" alt=\"\" width=\"383\" height=\"547\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada_Concepcion_La_Colosal-210x300.jpg 210w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada_Concepcion_La_Colosal.jpg 420w\" sizes=\"auto, (max-width: 383px) 100vw, 383px\" \/><\/p>\n<p style=\"text-align: center;\"><em><strong>La Inmaculada Concepci\u00f3n \u201cLa Colosal\u201d. 1650.\u00a0\u00d3leo sobre lienzo.\u00a0436 x 297 cm. Museo de Bellas artes de Sevilla.<\/strong><\/em><\/p>\n<p style=\"text-align: center;\"><em>Esta obra se expone en el Museo de Bellas Artes de Sevilla, estando hasta la llegada de El jubileo de la Porci\u00fancula, de cuadro central del retablo mayor de la que fue iglesia del Convento de la Merced Calzada, y ahora en la entrada a la capilla principal en el lado del evangelio.<\/em><\/p>\n<p style=\"text-align: justify;\">El resto, est\u00e1n por diferentes museos, <strong><em>exponiendo en el Ayuntamiento de Sevilla\u00a0 -lugar\u00a0 en donde estuvo el convento- <span style=\"color: #ff0000;\">reproducciones<\/span> de todas ellas.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Las pinturas que formaron esta colecci\u00f3n del Claustro peque\u00f1o fueron:<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5125\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/extasis-san-francisco-de-asis2-confortado-1-300x282.jpg\" alt=\"\" width=\"472\" height=\"444\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/extasis-san-francisco-de-asis2-confortado-1-300x282.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/extasis-san-francisco-de-asis2-confortado-1.jpg 400w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Francisco confortado por un \u00e1ngel. 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 172 x 183 cm. Real Academia de Bellas Artes de San Fernando. Madrid.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>\u00a0La obra muestra a San Francisco de As\u00eds en un episodio de los \u00faltimos d\u00edas de su vida, en el que, estando enfermo y dolorido, fue asistido por un \u00e1ngel\/m\u00fasico como recompensa a su virtuosa vida.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5118\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-de-alcala-dando-de-comer-300x282.jpg\" alt=\"\" width=\"457\" height=\"430\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-de-alcala-dando-de-comer-300x282.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-de-alcala-dando-de-comer.jpg 400w\" sizes=\"auto, (max-width: 457px) 100vw, 457px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Diego de Alcal\u00e1 dando de comer a los pobres. 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 172 x 183 cm. Real Academia de Bellas Artes de San Fernando. Madrid.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>El protagonista es el fraile sevillano San Diego de Alcal\u00e1, encargado de repartir las sobras de las comidas del convento entre los numerosos pobres de Sevilla que acud\u00edan a la puerta del convento para recoger comida.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5119\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-en-extasis-delante-de-lacruz-300x280.jpg\" alt=\"\" width=\"456\" height=\"426\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-en-extasis-delante-de-lacruz-300x280.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-diego-en-extasis-delante-de-lacruz.jpg 567w\" sizes=\"auto, (max-width: 456px) 100vw, 456px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Diego de Alcal\u00e1 en \u00e9xtasis delante de la cruz. 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 172 x 184\u00a0 cm. Mus\u00e9e des Augustins. Toulouse. Francia.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>San Diego de Alcal\u00e1 protagonista de esta pintura en la que se muestra un episodio milagroso que acontec\u00eda cuando el fraile trabajaba en el huerto del convento; all\u00ed, concentrado en sus meditaciones, entraba en \u00e9xtasis y comenzaba a levitar cuando estaba cerca una cruz de madera. Murillo introduce a varios personajes como testigos del milagro, pudi\u00e9ndose reconocer a don Agust\u00edn de Sp\u00ednola, Arzobispo de Sevilla en 1645, acompa\u00f1ado por dos personajes y los franciscanos fray Pedro de Almaguer y fray Francisco de la Cruz.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5131 aligncenter\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-gil-en-extasis-ante-el-papa-gregorio-IX-300x267.jpg\" alt=\"\" width=\"436\" height=\"388\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-gil-en-extasis-ante-el-papa-gregorio-IX-300x267.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/san-gil-en-extasis-ante-el-papa-gregorio-IX.jpg 640w\" sizes=\"auto, (max-width: 436px) 100vw, 436px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Gil en \u00e9xtasis ante el Papa Gregorio IX. 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 166 x 186 cm. North Carolina Museum of Art. Raleight, USA.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>Las levitaciones de este fraile fueron conocidas por el Papa Gregorio IX, que quiso ser testigo del milagro y convoc\u00f3 al fraile a su presencia. Cuando el papa pronunci\u00f3 la palabra \u201ccielo\u201d, San Gil entr\u00f3 en trance, elev\u00e1ndose sobre el suelo, sorprendiendo a todos por su profunda espiritualidad.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5109\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/09-Visi\u00f3n-de-fray-Juli\u00e1n-de-Alcal\u00e1-de-la-ascensi\u00f3n-del-alma-de-Felipe-II-Art-Institute-in-Williamstown-170x187-cm-300x272.jpg\" alt=\"\" width=\"424\" height=\"384\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/09-Visi\u00f3n-de-fray-Juli\u00e1n-de-Alcal\u00e1-de-la-ascensi\u00f3n-del-alma-de-Felipe-II-Art-Institute-in-Williamstown-170x187-cm-300x272.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/09-Visi\u00f3n-de-fray-Juli\u00e1n-de-Alcal\u00e1-de-la-ascensi\u00f3n-del-alma-de-Felipe-II-Art-Institute-in-Williamstown-170x187-cm.jpg 320w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>La visi\u00f3n de fray Juan de Alcal\u00e1 de la ascensi\u00f3n del alma de Felipe II.<\/em>\u00a0 <em>1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 170 x 187 cm. Sterling and Francine Clark Art Institute. Williamstown.Massachusetts. USA.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>En la composici\u00f3n, fray Juan de Alcal\u00e1 muestra a un grupo de testigos el milagro que predijo y que est\u00e1 aconteciendo ante sus asombrados ojos: sobre una ciudad amurallada, el alma del Felipe II es acogida por una corte celestial.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5110\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/10-Fray-Junipero-y-el-pobre-Museo-del-Louvre-1-300x240.jpg\" alt=\"\" width=\"403\" height=\"322\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/10-Fray-Junipero-y-el-pobre-Museo-del-Louvre-1-300x240.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/10-Fray-Junipero-y-el-pobre-Museo-del-Louvre-1.jpg 320w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Fray Jun\u00edpero y el pobre<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 176 x 221 cm. Museo del Louvre. Par\u00eds.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>El car\u00e1cter desprendido del fraile era tal, que no dudaba en dar todo lo que ten\u00eda a los pobres, incluso sus vestimentas, llegando al convento cada d\u00eda pr\u00e1cticamente desnudo. Como los superiores le prohibieron desprenderse de su h\u00e1bito, cuando encontr\u00f3 a un pobre vestido con harapos le se\u00f1al\u00f3 que no pod\u00eda darle su ropa, pero que, si \u00e9l se los quitaba, no opondr\u00eda resistencia. \u00c9sta es la escena narrada por Murillo, en la que el fraile deja que el mendigo le quite sus vestimentas.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5108\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/03-San-Salvador-de-Horta-y-el-inquisidor-de-Arag\u00f3n-Mus\u00e9e-Bonnat-Bayonne-300x282.jpg\" alt=\"\" width=\"393\" height=\"369\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/03-San-Salvador-de-Horta-y-el-inquisidor-de-Arag\u00f3n-Mus\u00e9e-Bonnat-Bayonne-300x282.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/03-San-Salvador-de-Horta-y-el-inquisidor-de-Arag\u00f3n-Mus\u00e9e-Bonnat-Bayonne.jpg 320w\" sizes=\"auto, (max-width: 393px) 100vw, 393px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Salvador de Horta y el Inquisidor de Arag\u00f3n.<\/em>\u00a0<em>1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 178 x 190 cm. Museo Bonnat. Bayona. Francia.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>San Salvador de Horta, fraile franciscano conocido por su modestia y venerado por sus milagros para devolver la salud, despert\u00f3 el inter\u00e9s del inquisidor de Arag\u00f3n, quien quiso verificar la correcci\u00f3n espiritual de sus milagros. Para ello, se visti\u00f3 con ropas laicas y solicit\u00f3 la asistencia del fraile para aliviar sus dolencias. En ese momento, como muestra la pintura del artista, San Salvador de Horta reconoci\u00f3, por inspiraci\u00f3n divina, al inquisidor y se arrodill\u00f3 a sus pies en se\u00f1al de respeto y humildad.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5126\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/La-curaci\u00f3n-milagrosa-de-fray-juan-de-la-cruz-1-205x300.jpg\" alt=\"\" width=\"350\" height=\"512\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/La-curaci\u00f3n-milagrosa-de-fray-juan-de-la-cruz-1-205x300.jpg 205w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/La-curaci\u00f3n-milagrosa-de-fray-juan-de-la-cruz-1-768x1124.jpg 768w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/La-curaci\u00f3n-milagrosa-de-fray-juan-de-la-cruz-1-700x1024.jpg 700w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/La-curaci\u00f3n-milagrosa-de-fray-juan-de-la-cruz-1.jpg 820w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>La curaci\u00f3n milagrosa obrada por fray Juan de la Cruz.<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 156 x 106 cm. National Gallery of Canad\u00e1. Otawa. Canad\u00e1.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>El fraile vivi\u00f3 en el convento franciscano hispalense a comienzos del siglo XVI, cuando la ciudad fue devastada por la epidemia de peste de 1524, en la que intervino realizando numerosas curaciones milagrosas. En la pintura, el santo aparece invocando la ayuda divina para sanar al monje franciscano que, inconsciente, yace a sus pies.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5138\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/07-La-cocina-de-los-angeles-180x450-Museo-del-Louvre-1-300x119.jpg\" alt=\"\" width=\"628\" height=\"249\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/07-La-cocina-de-los-angeles-180x450-Museo-del-Louvre-1-300x119.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/07-La-cocina-de-los-angeles-180x450-Museo-del-Louvre-1.jpg 320w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Fray Francisco y la cocina de los \u00e1ngeles.<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 180 x 450 cm. Museo del Louvre. Par\u00eds.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>Es esta pintura una de las m\u00e1s hermosas composiciones realizadas por Murillo en su trayectoria creativa y de las m\u00e1s importantes del Claustro de San Francisco.<\/em><br \/>\n<em>El protagonista es, probablemente, fray Francisco P\u00e9rez, cocinero del Convento de San Francisco, quien realizaba sus tareas en la cocina con tanto fervor que entraba en trance, levitando y olvidando sus obligaciones. Esto as\u00ed, un grupo de \u00e1ngeles se encargaba de preparar la comida para que estuviera preparada a su hora.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5106\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/08-La-muerte-de-Santa-Clara-Gemaldegallerie-Dresden-190-X-446-cm-300x124.jpg\" alt=\"\" width=\"603\" height=\"249\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/08-La-muerte-de-Santa-Clara-Gemaldegallerie-Dresden-190-X-446-cm-300x124.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/08-La-muerte-de-Santa-Clara-Gemaldegallerie-Dresden-190-X-446-cm-768x317.jpg 768w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/08-La-muerte-de-Santa-Clara-Gemaldegallerie-Dresden-190-X-446-cm.jpg 900w\" sizes=\"auto, (max-width: 603px) 100vw, 603px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>La muerte de Santa Clara.<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 189 x 446 cm. Gem\u00e4ldegalerie Alte Meister. Dresde. Alemania.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>La obra rinde homenaje a la grandeza espiritual de la orden franciscana, en esta ocasi\u00f3n, a trav\u00e9s de Santa Clara de As\u00eds, seguidora de San Francisco y fundadora de la Segunda orden franciscana. Al mismo tiempo, la pintura muestra la dignificaci\u00f3n de la muerte por parte de los franciscanos, celebrada como un tr\u00e1nsito feliz hacia el cielo.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5117\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada-FrayJuandeQuiros1-300x212.jpg\" alt=\"\" width=\"461\" height=\"326\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada-FrayJuandeQuiros1-300x212.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Inmaculada-FrayJuandeQuiros1.jpg 640w\" sizes=\"auto, (max-width: 461px) 100vw, 461px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Inmaculada con fray Juan de Quir\u00f3s.<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 241 x 341 cm. Palacio Arzobispal. Sevilla.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>Fray Juan de Quir\u00f3s naci\u00f3 en Osuna. En 1616 tom\u00f3 el h\u00e1bito franciscano y tuvo diversos cargos de importancia en la orden de San Francisco y en el Santo Oficio. Se distingui\u00f3 como ferviente defensor de la Virgen, en cuya defensa escribi\u00f3 una obra con dos tomos que aparecen en la pintura.<\/em><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5137\" src=\"http:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/06-San-Francisco-Solano-y-el-toro.-Murillo-1645.-Reales-Alc\u00e1zares.-Sevilla.-Patrimonio-Nacional-300x203.jpg\" alt=\"\" width=\"567\" height=\"384\" srcset=\"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/06-San-Francisco-Solano-y-el-toro.-Murillo-1645.-Reales-Alc\u00e1zares.-Sevilla.-Patrimonio-Nacional-300x203.jpg 300w, https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/06-San-Francisco-Solano-y-el-toro.-Murillo-1645.-Reales-Alc\u00e1zares.-Sevilla.-Patrimonio-Nacional.jpg 320w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>San Francisco Solano y el toro.<\/em>\u00a0<em> 1644-1646. \u00d3leo sobre lienzo. (REPRODUCCI\u00d3N DEL ORIGINAL). 157 x 225 cm. Original en el Real Alc\u00e1zar. Sevilla.<\/em><\/strong><\/p>\n<p style=\"text-align: center;\"><em>Esta pintura <strong>no form\u00f3 parte de la decoraci\u00f3n del claustro chico, sin embargo s\u00ed fue ejecutada para la orden franciscana y debi\u00f3 de estar dispuesta en el recinto conventual.<\/strong><\/em><br \/>\n<em>El protagonista es el fraile San Francisco Solano quien, estando como misionero en el Convento de la Recolecci\u00f3n franciscana de Lima, someti\u00f3, de forma milagrosa, a un toro que amenazaba a los habitantes de la localidad. En la pintura, aparece el santo, que, ante el asombro general, ha atado los cuernos del animal con el cord\u00f3n de su h\u00e1bito y ha conseguido devolverlo a su encierro.<\/em><\/p>\n<p style=\"text-align: center;\"><em><strong>To be continued in part 4.<\/strong><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el solar en el que est\u00e1, la hoy conocida como Plaza\u00a0 Nueva,\u00a0 se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo,\u00a0 cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del\u00a0 Convento Casa Grande de San Francisco,<\/p>\n","protected":false},"author":2,"featured_media":5114,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_mo_disable_npp":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1,21],"tags":[852,885,878,695,884,880,881,883,882],"class_list":["post-5089","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-la-emocion-del-arte","category-pintura","tag-bartolome-esteban-murillo","tag-capilla-de-las-animas-de-san-onofre","tag-convento-casa-grande-de-san-francisco","tag-fernando-iii-el-santo","tag-iglesia-del-sagrario-de-la-catedral-de-sevilla","tag-la-inmaculada-la-colosal","tag-plaza-nueva","tag-retablo-de-los-vizcainos","tag-san-onofre"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"yo te pintaria as\u00ed si yo pudiera\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Los cordones que me ato cada d\u00eda -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda\" \/>\n\t\t<meta property=\"og:description\" content=\"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2019-04-13T08:00:20+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2019-04-08T16:15:31+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#blogposting\",\"name\":\"BARTOLOM\\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\\u00eda\",\"headline\":\"BARTOLOM\\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.\",\"author\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Casa-Grande-1.jpg\",\"width\":268,\"height\":188},\"datePublished\":\"2019-04-13T09:00:20+01:00\",\"dateModified\":\"2019-04-08T17:15:31+01:00\",\"inLanguage\":\"es-ES\",\"commentCount\":1,\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#webpage\"},\"articleSection\":\"La emoci\\u00f3n del Arte, Pintura, Bartolom\\u00e9 Esteban Murillo, Capilla de las \\u00c1nimas de san Onofre, Convento Casa Grande de San Francisco, Fernando III El Santo, Iglesia del Sagrario de la Catedral de Sevilla, La Inmaculada La Colosal, Plaza Nueva, Retablo de los Vizcainos, San Onofre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"name\":\"La emoci\\u00f3n del Arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"position\":2,\"name\":\"La emoci\\u00f3n del Arte\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/pintura\\\/#listItem\",\"name\":\"Pintura\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/pintura\\\/#listItem\",\"position\":3,\"name\":\"Pintura\",\"item\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/pintura\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#listItem\",\"name\":\"BARTOLOM\\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/#listItem\",\"name\":\"La emoci\\u00f3n del Arte\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#listItem\",\"position\":4,\"name\":\"BARTOLOM\\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/category\\\/la-emocion-del-arte\\\/pintura\\\/#listItem\",\"name\":\"Pintura\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\",\"name\":\"Los cordones que me ato cada d\\u00eda\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/\",\"name\":\"yo te pintaria as\\u00ed si yo pudiera\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/93f26e5685ea82b42201c127a33bb86aa2a372bbec04d1a3a74cab90e8beb2c0?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"yo te pintaria as\\u00ed si yo pudiera\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#webpage\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/\",\"name\":\"BARTOLOM\\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\\u00eda\",\"description\":\"En el solar en el que est\\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\\u00f3 a construirse en los a\\u00f1os\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/author\\\/yotepintariaasisiyopudiera\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/wp-content\\\/uploads\\\/2018\\\/10\\\/Casa-Grande-1.jpg\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#mainImage\",\"width\":268,\"height\":188},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/2019\\\/04\\\/13\\\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\\\/#mainImage\"},\"datePublished\":\"2019-04-13T09:00:20+01:00\",\"dateModified\":\"2019-04-08T17:15:31+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/\",\"name\":\"Los cordones que me ato cada d\\u00eda\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/loscordonesquemeatocadadia.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda","description":"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os","canonical_url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#blogposting","name":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda","headline":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.","author":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"publisher":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Casa-Grande-1.jpg","width":268,"height":188},"datePublished":"2019-04-13T09:00:20+01:00","dateModified":"2019-04-08T17:15:31+01:00","inLanguage":"es-ES","commentCount":1,"mainEntityOfPage":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#webpage"},"isPartOf":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#webpage"},"articleSection":"La emoci\u00f3n del Arte, Pintura, Bartolom\u00e9 Esteban Murillo, Capilla de las \u00c1nimas de san Onofre, Convento Casa Grande de San Francisco, Fernando III El Santo, Iglesia del Sagrario de la Catedral de Sevilla, La Inmaculada La Colosal, Plaza Nueva, Retablo de los Vizcainos, San Onofre"},{"@type":"BreadcrumbList","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es#listItem","position":1,"name":"Home","item":"https:\/\/loscordonesquemeatocadadia.com\/es","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","name":"La emoci\u00f3n del Arte"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","position":2,"name":"La emoci\u00f3n del Arte","item":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/#listItem","name":"Pintura"},"previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/#listItem","position":3,"name":"Pintura","item":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/","nextItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#listItem","name":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4."},"previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/#listItem","name":"La emoci\u00f3n del Arte"}},{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#listItem","position":4,"name":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.","previousItem":{"@type":"ListItem","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/#listItem","name":"Pintura"}}]},{"@type":"Organization","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization","name":"Los cordones que me ato cada d\u00eda","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/"},{"@type":"Person","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/","name":"yo te pintaria as\u00ed si yo pudiera","image":{"@type":"ImageObject","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/93f26e5685ea82b42201c127a33bb86aa2a372bbec04d1a3a74cab90e8beb2c0?s=96&d=mm&r=g","width":96,"height":96,"caption":"yo te pintaria as\u00ed si yo pudiera"}},{"@type":"WebPage","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#webpage","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/","name":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda","description":"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#breadcrumblist"},"author":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"creator":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/author\/yotepintariaasisiyopudiera\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-content\/uploads\/2018\/10\/Casa-Grande-1.jpg","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#mainImage","width":268,"height":188},"primaryImageOfPage":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/#mainImage"},"datePublished":"2019-04-13T09:00:20+01:00","dateModified":"2019-04-08T17:15:31+01:00"},{"@type":"WebSite","@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#website","url":"https:\/\/loscordonesquemeatocadadia.com\/es\/","name":"Los cordones que me ato cada d\u00eda","inLanguage":"es-ES","publisher":{"@id":"https:\/\/loscordonesquemeatocadadia.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Los cordones que me ato cada d\u00eda -","og:type":"article","og:title":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda","og:description":"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os","og:url":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/","article:published_time":"2019-04-13T08:00:20+00:00","article:modified_time":"2019-04-08T16:15:31+00:00","twitter:card":"summary_large_image","twitter:title":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4. - Los cordones que me ato cada d\u00eda","twitter:description":"En el solar en el que est\u00e1, la hoy conocida como Plaza Nueva, se encuentra el Ayuntamiento de Sevilla y la estatua de Fernando III El Santo, cuyo espacio central parece que coincide con el lugar donde estuvo el altar mayor del Convento Casa Grande de San Francisco, que empez\u00f3 a construirse en los a\u00f1os"},"aioseo_meta_data":{"post_id":"5089","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-05-04 10:50:23","updated":"2025-06-13 16:52:08","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/\" title=\"La emoci\u00f3n del Arte\">La emoci\u00f3n del Arte<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/\" title=\"Pintura\">Pintura<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tBARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/loscordonesquemeatocadadia.com\/es"},{"label":"La emoci\u00f3n del Arte","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/"},{"label":"Pintura","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/category\/la-emocion-del-arte\/pintura\/"},{"label":"BARTOLOM\u00c9 ESTEBAN MURILLO: Tras los  pasos de Murillo; las obras que se crearon para el convento de san Francisco, sus reproducciones, est\u00e1n expuestas en el Ayuntamiento de Sevilla. Parte 4.","link":"https:\/\/loscordonesquemeatocadadia.com\/es\/2019\/04\/13\/bartolome-esteban-murillo-tras-los-pasos-de-murillo-las-obras-del-convento-de-san-francisco-expuestas-sus-reproducciones-en-el-ayuntamiento-de-sevilla-parte-4\/"}],"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/5089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/comments?post=5089"}],"version-history":[{"count":18,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/5089\/revisions"}],"predecessor-version":[{"id":6243,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/posts\/5089\/revisions\/6243"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/media\/5114"}],"wp:attachment":[{"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/media?parent=5089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/categories?post=5089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loscordonesquemeatocadadia.com\/es\/wp-json\/wp\/v2\/tags?post=5089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}